{"id":9631,"count":1,"description":"","link":"https:\/\/orkus1.com\/en\/tag\/51st-state\/","name":"51st State","slug":"51st-state","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>51st State Archive - Orkus1.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orkus1.com\/en\/tag\/51st-state\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"51st State Archive - Orkus1.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orkus1.com\/en\/tag\/51st-state\/\" \/>\n<meta property=\"og:site_name\" content=\"Orkus1.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/orkus1.com\/en\/tag\/51st-state\/\",\"url\":\"https:\/\/orkus1.com\/en\/tag\/51st-state\/\",\"name\":\"51st State Archive - Orkus1.com\",\"isPartOf\":{\"@id\":\"https:\/\/orkus1.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/orkus1.com\/en\/tag\/51st-state\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/orkus1.com\/en\/tag\/51st-state\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/orkus1.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"51st State\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/orkus1.com\/en\/#website\",\"url\":\"https:\/\/orkus1.com\/en\/\",\"name\":\"Orkus1.com\",\"description\":\"The darker side of music\",\"publisher\":{\"@id\":\"https:\/\/orkus1.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/orkus1.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/orkus1.com\/en\/#organization\",\"name\":\"Orkus1.com\",\"url\":\"https:\/\/orkus1.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/orkus1.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/orkus1.com\/wp-content\/uploads\/2023\/03\/logo-orkus.png\",\"contentUrl\":\"https:\/\/orkus1.com\/wp-content\/uploads\/2023\/03\/logo-orkus.png\",\"width\":724,\"height\":164,\"caption\":\"Orkus1.com\"},\"image\":{\"@id\":\"https:\/\/orkus1.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"51st State Archive - Orkus1.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orkus1.com\/en\/tag\/51st-state\/","og_locale":"en_US","og_type":"article","og_title":"51st State Archive - Orkus1.com","og_url":"https:\/\/orkus1.com\/en\/tag\/51st-state\/","og_site_name":"Orkus1.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/orkus1.com\/en\/tag\/51st-state\/","url":"https:\/\/orkus1.com\/en\/tag\/51st-state\/","name":"51st State Archive - Orkus1.com","isPartOf":{"@id":"https:\/\/orkus1.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/orkus1.com\/en\/tag\/51st-state\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/orkus1.com\/en\/tag\/51st-state\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/orkus1.com\/en\/"},{"@type":"ListItem","position":2,"name":"51st State"}]},{"@type":"WebSite","@id":"https:\/\/orkus1.com\/en\/#website","url":"https:\/\/orkus1.com\/en\/","name":"Orkus1.com","description":"The darker side of music","publisher":{"@id":"https:\/\/orkus1.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orkus1.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/orkus1.com\/en\/#organization","name":"Orkus1.com","url":"https:\/\/orkus1.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/orkus1.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/orkus1.com\/wp-content\/uploads\/2023\/03\/logo-orkus.png","contentUrl":"https:\/\/orkus1.com\/wp-content\/uploads\/2023\/03\/logo-orkus.png","width":724,"height":164,"caption":"Orkus1.com"},"image":{"@id":"https:\/\/orkus1.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/orkus1.com\/en\/wp-json\/wp\/v2\/tags\/9631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orkus1.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/orkus1.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/orkus1.com\/en\/wp-json\/wp\/v2\/posts?tags=9631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}